{"id":8900,"date":"2022-01-11T10:46:48","date_gmt":"2022-01-11T08:46:48","guid":{"rendered":"https:\/\/lev-development.com.ua\/?page_id=8900"},"modified":"2025-01-27T14:19:04","modified_gmt":"2025-01-27T12:19:04","slug":"lev-liveride","status":"publish","type":"page","link":"https:\/\/lev-development.com.ua\/en\/lev-liveride\/","title":{"rendered":"LEV Live&#038;Ride"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":9076,"parent":0,"menu_order":4,"comment_status":"closed","ping_status":"closed","template":"page-complex-arhouse.php","meta":{"inline_featured_image":false},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.13 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>LEV Live&amp;Ride - LEV Development (\u041b\u0435\u0432 \u0414\u0435\u0432\u0435\u043b\u043e\u043f\u043c\u0435\u043d\u0442)<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lev-development.com.ua\/en\/wp-json\/wp\/v2\/pages\/8900\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LEV Live&amp;Ride\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lev-development.com.ua\/en\/lev-liveride\/\" \/>\n<meta property=\"og:site_name\" content=\"LEV Development (\u041b\u0435\u0432 \u0414\u0435\u0432\u0435\u043b\u043e\u043f\u043c\u0435\u043d\u0442)\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-27T12:19:04+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/lev-development.com.ua\/wp-content\/uploads\/2022\/01\/image_part_006.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"1073\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/lev-development.com.ua\/en\/lev-liveride\/\",\"url\":\"https:\/\/lev-development.com.ua\/en\/lev-liveride\/\",\"name\":\"[:uk]LEV Live&Ride[:en]LEV Live&Ride[:ru]LEV Live&Ride[:] - LEV Development (\u041b\u0435\u0432 \u0414\u0435\u0432\u0435\u043b\u043e\u043f\u043c\u0435\u043d\u0442)\",\"isPartOf\":{\"@id\":\"https:\/\/lev-development.com.ua\/#website\"},\"datePublished\":\"2022-01-11T08:46:48+00:00\",\"dateModified\":\"2025-01-27T12:19:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/lev-development.com.ua\/en\/lev-liveride\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/lev-development.com.ua\/en\/lev-liveride\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/lev-development.com.ua\/en\/lev-liveride\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0413\u043e\u043b\u043e\u0432\u043d\u0430 \u0421\u0442\u043e\u0440\u0456\u043d\u043a\u0430\",\"item\":\"https:\/\/lev-development.com.ua\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LEV Live&#038;Ride\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/lev-development.com.ua\/#website\",\"url\":\"https:\/\/lev-development.com.ua\/\",\"name\":\"LEV Development (\u041b\u0435\u0432 \u0414\u0435\u0432\u0435\u043b\u043e\u043f\u043c\u0435\u043d\u0442)\",\"description\":\"\u041f\u0440\u043e\u0434\u0430\u0436 \u043a\u0432\u0430\u0440\u0442\u0438\u0440 \u0442\u0430 \u0456\u043d\u0432\u0435\u0441\u0442\u0438\u0446\u0456\u0439\u043d\u043e\u0457 \u043d\u0435\u0440\u0443\u0445\u043e\u043c\u043e\u0441\u0442\u0456\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/lev-development.com.ua\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-GB\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LEV Live&Ride - LEV Development (\u041b\u0435\u0432 \u0414\u0435\u0432\u0435\u043b\u043e\u043f\u043c\u0435\u043d\u0442)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lev-development.com.ua\/en\/wp-json\/wp\/v2\/pages\/8900","og_locale":"en_GB","og_type":"article","og_title":"[:uk]LEV Live&Ride[:en]LEV Live&Ride[:ru]LEV Live&Ride[:] - LEV Development (\u041b\u0435\u0432 \u0414\u0435\u0432\u0435\u043b\u043e\u043f\u043c\u0435\u043d\u0442)","og_url":"https:\/\/lev-development.com.ua\/en\/lev-liveride\/","og_site_name":"LEV Development (\u041b\u0435\u0432 \u0414\u0435\u0432\u0435\u043b\u043e\u043f\u043c\u0435\u043d\u0442)","article_modified_time":"2025-01-27T12:19:04+00:00","og_image":[{"width":500,"height":1073,"url":"http:\/\/lev-development.com.ua\/wp-content\/uploads\/2022\/01\/image_part_006.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lev-development.com.ua\/en\/lev-liveride\/","url":"https:\/\/lev-development.com.ua\/en\/lev-liveride\/","name":"[:uk]LEV Live&Ride[:en]LEV Live&Ride[:ru]LEV Live&Ride[:] - LEV Development (\u041b\u0435\u0432 \u0414\u0435\u0432\u0435\u043b\u043e\u043f\u043c\u0435\u043d\u0442)","isPartOf":{"@id":"https:\/\/lev-development.com.ua\/#website"},"datePublished":"2022-01-11T08:46:48+00:00","dateModified":"2025-01-27T12:19:04+00:00","breadcrumb":{"@id":"https:\/\/lev-development.com.ua\/en\/lev-liveride\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lev-development.com.ua\/en\/lev-liveride\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/lev-development.com.ua\/en\/lev-liveride\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0413\u043e\u043b\u043e\u0432\u043d\u0430 \u0421\u0442\u043e\u0440\u0456\u043d\u043a\u0430","item":"https:\/\/lev-development.com.ua\/"},{"@type":"ListItem","position":2,"name":"LEV Live&#038;Ride"}]},{"@type":"WebSite","@id":"https:\/\/lev-development.com.ua\/#website","url":"https:\/\/lev-development.com.ua\/","name":"LEV Development (\u041b\u0435\u0432 \u0414\u0435\u0432\u0435\u043b\u043e\u043f\u043c\u0435\u043d\u0442)","description":"\u041f\u0440\u043e\u0434\u0430\u0436 \u043a\u0432\u0430\u0440\u0442\u0438\u0440 \u0442\u0430 \u0456\u043d\u0432\u0435\u0441\u0442\u0438\u0446\u0456\u0439\u043d\u043e\u0457 \u043d\u0435\u0440\u0443\u0445\u043e\u043c\u043e\u0441\u0442\u0456","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lev-development.com.ua\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-GB"}]}},"_links":{"self":[{"href":"https:\/\/lev-development.com.ua\/en\/wp-json\/wp\/v2\/pages\/8900"}],"collection":[{"href":"https:\/\/lev-development.com.ua\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lev-development.com.ua\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lev-development.com.ua\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lev-development.com.ua\/en\/wp-json\/wp\/v2\/comments?post=8900"}],"version-history":[{"count":110,"href":"https:\/\/lev-development.com.ua\/en\/wp-json\/wp\/v2\/pages\/8900\/revisions"}],"predecessor-version":[{"id":14205,"href":"https:\/\/lev-development.com.ua\/en\/wp-json\/wp\/v2\/pages\/8900\/revisions\/14205"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lev-development.com.ua\/en\/wp-json\/wp\/v2\/media\/9076"}],"wp:attachment":[{"href":"https:\/\/lev-development.com.ua\/en\/wp-json\/wp\/v2\/media?parent=8900"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}